{"id":56,"date":"2018-11-30T20:46:43","date_gmt":"2018-11-30T22:46:43","guid":{"rendered":"http:\/\/localhost\/cdh\/?page_id=56"},"modified":"2024-04-26T08:29:14","modified_gmt":"2024-04-26T11:29:14","slug":"tecnicas","status":"publish","type":"page","link":"https:\/\/clinicadh.direito.ufmg.br\/index.php\/tecnicas\/","title":{"rendered":"Produ\u00e7\u00f5es T\u00e9cnicas"},"content":{"rendered":"<h3><\/h3>\n<h3><a href=\"https:\/\/drive.google.com\/file\/d\/1LrOG96SJmROBVcK_L7xc86yTA6drjfHm\/view?usp=sharing\" target=\"_blank\" rel=\"noopener noreferrer\">&#8211; Amicus Curiae (memorial de) &#8211; \u00e0 Corte Interamericana de Direitos Humanos na Opini\u00e3o Consultiva n\u00ba 32<\/a><\/h3>\n<p><span style=\"font-weight: 400;\">Amicus curiae elaborado pela CdH\/UFMG na Opini\u00e3o Consultiva solicitada pelos Estados da Col\u00f4mbia e da Costa Rica sobre Emerg\u00eancia Clim\u00e1tica e Direitos Humanos [2024]<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><a href=\"https:\/\/drive.google.com\/file\/d\/1nYEX2ic46x51-H3zuRepkE-5ECG1R3uQ\/view?usp=sharing\" target=\"_blank\" rel=\"noopener noreferrer\">&#8211; Amicus Curiae (memorial de) &#8211; \u00e0 Corte Interamericana de Direitos Humanos na Opini\u00e3o Consultiva n\u00ba 31<\/a><\/h3>\n<p><span style=\"font-weight: 400;\">Amicus curiae elaborado por CdH\/UFMG, Diverso UFMG &#8211; N\u00facleo Jur\u00eddico de Diversidade Sexual e de G\u00eanero e N\u00facleo de Ensino, Pesquisa e Extens\u00e3o Conex\u00f5es de Saberes na Opini\u00e3o Consultiva solicitada pelo Estado da Argentina \u00e0 Corte Interamericana de Direitos Humanos sobre direito ao cuidado [2024]<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><a href=\"https:\/\/drive.google.com\/file\/d\/1lXWAZQO7prnG5fyJDObRRvUNxqgGZxy-\/view?usp=sharing\">&#8211; Relat\u00f3rio Transpasse (2020-2022)<\/a><\/h3>\n<p>Relat\u00f3rio de Atividades do Projeto Transpasse (2020-2022) [2023]<\/p>\n<p>&nbsp;<\/p>\n<h3><a href=\"https:\/\/drive.google.com\/file\/d\/1VipcPDO9P6Ftx2Bd5c4p5K7KRpqq9DkV\/view?usp=sharing\">&#8211; Resposta da CdH\/UFMG ao question\u00e1rio &#8220;setor extrativista, transi\u00e7\u00e3o justa e direitos humanos&#8221;<\/a><\/h3>\n<p>Resposta da CdH\/UFMG ao <em>Working Group of Business and Human Rights\u2019 call for input on the extractive sector, just transition and human rights<\/em>\u00a0[em ingl\u00eas] [2023]<\/p>\n<p>&nbsp;<\/p>\n<h3><a href=\"https:\/\/www.dropbox.com\/s\/kzvi1tcqji0p91a\/Devida%20dilig%C3%AAncia%20-%20Fallstudie%20Eisenerz_DKA%20OEFSE%20CdH%20UFMG_2022_screen.pdf?dl=0\">&#8211; Direitos humanos e prote\u00e7\u00e3o ambiental em cadeias de fornecimento de min\u00e9rio de ferro<\/a><\/h3>\n<p>Relat\u00f3rio t\u00e9cnico [em alem\u00e3o] [2022]<\/p>\n<p>&nbsp;<\/p>\n<h3><a href=\"https:\/\/drive.google.com\/file\/d\/1JDWZADV5LTJMxFeXWOEo8_sLxgJuJiQ2\/view?usp=sharing\">&#8211; Relat\u00f3rio T\u00e9cnico COINTER<\/a><\/h3>\n<p>Relat\u00f3rio T\u00e9cnico Cons\u00f3rcio-Observat\u00f3rio Interamericano (COINTER) [2022]<\/p>\n<p>&nbsp;<\/p>\n<h3><a href=\"https:\/\/www.dropbox.com\/s\/g02paoc6t9smz2r\/CdH_UFMG%20-%20DDHH%20e%20Empresas%20-%20Aportes%20ao%20instrumento%20vinculante_2021.docx.pdf?dl=0\">&#8211; Aportes ao Processo de Negocia\u00e7\u00e3o do Instrumento Vinculante Sobre Empresas e Direitos Humanos no \u00c2mbito das Na\u00e7\u00f5es Unidas<\/a><\/h3>\n<p>O documento, produzido em parceria com a DKA \u00c1ustria, ilustra algumas das disposi\u00e7\u00f5es da segunda vers\u00e3o revisada do rascunho de tratado vinculante, \u00e0 luz dos dois maiores desastres socioambientais e tecnol\u00f3gicos causados pelo setor de minera\u00e7\u00e3o no mundo, ambos recentes e ocorridos\u00a0 no Brasil [2021]<\/p>\n<p>&nbsp;<\/p>\n<h3><a href=\"https:\/\/www.dropbox.com\/s\/4rwjot0ybd8tuyq\/CdH_UFMG%20-%20DDHH%20e%20Empresas%20-%20Aportes%20ao%20instrumento%20vinculante_eng_2021.pdf?dl=0\">&#8211; Contributions to the Process of Negotiation of the Binding Instrument on Business and Human Rights at the United Nations<\/a><\/h3>\n<p>The document, produced in partnership with DKA Austria, illustrates some of the provisions of the second revised version of the draft binding treaty, in light of the two largest socio-environmental and technological disasters caused by the mining sector in the world, both recent and occurring in Brazil [2021]<\/p>\n<p>&nbsp;<\/p>\n<h3><a href=\"https:\/\/www.dropbox.com\/s\/jl8kjl1iexh5v8x\/Justificativa%20altera%C3%A7%C3%B5es%20PL%204.880_17.pdf?dl=0\">&#8211; Nota T\u00e9cnica sobre PL 4880\/2017 (sancionada como Lei 23.780\/2021): <\/a><\/h3>\n<p>Nota t\u00e9cnica produzida em conjunto com a Coletiva M\u00e3es \u00d3rf\u00e3s, propondo altera\u00e7\u00f5es no texto original do PL. A lei sancionada institui a pol\u00edtica estadual de aten\u00e7\u00e3o a gestantes, pu\u00e9rperas e crian\u00e7as, em situa\u00e7\u00e3o de vulnerabilidade e riscos social e pessoal [2020]<\/p>\n<p>&nbsp;<\/p>\n<h3><a href=\"https:\/\/www.dropbox.com\/s\/j1zxzsni1sknbzw\/Relat%C3%B3rio%20-%20Transpasse%202019.pdf?dl=0\">&#8211; Relat\u00f3rio do Projeto Transpasse<\/a><\/h3>\n<p><span style=\"font-size: 12pt;\">Sobre a assist\u00eancia jur\u00eddica e psicossocial a pessoas trans e travestis, em Belo Horizonte, oferecida pela Cl\u00ednica [2019]<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><a href=\"https:\/\/www.dropbox.com\/s\/y96d3ke65sc8bod\/Amicus%20Curiae%20CdH%20-%20ADI%205581%20.pdf?dl=0\">&#8211; Amicus Curiae &#8211; ADI n\u00b0 5581<\/a><\/h3>\n<p>Sobre a\u00e7\u00e3o que trata da interrup\u00e7\u00e3o da gesta\u00e7\u00e3o, em rela\u00e7\u00e3o \u00e0 mulher infectada pelo zika v\u00edrus, dentre outros assuntos [2019]<\/p>\n<p>&nbsp;<\/p>\n<h3><a href=\"https:\/\/www.dropbox.com\/s\/g3bflef3w3kz631\/Amicus%20Curiae%20ADPF%20442%20-%20CdH.pdf?dl=0\">&#8211; Amicus Curiae &#8211; ADPF n\u00b0 442<\/a><\/h3>\n<p>Sobre a\u00e7\u00e3o que trata da interrup\u00e7\u00e3o da gravidez at\u00e9 a 12\u00aa semana de gesta\u00e7\u00e3o [2018]<\/p>\n<p>&nbsp;<\/p>\n<h3 class=\"font_8\"><a href=\"https:\/\/crp04.org.br\/nota-tecnica-conjunta-direitos-de-maes-e-bebes-ao-tratamento-em-liberdade\/\">&#8211; Nota t\u00e9cnica conjunta\u00a0<\/a><\/h3>\n<p>Sobre direitos de m\u00e3es e beb\u00eas ao tratamento em liberdade. Referente \u00e0 proposta de interna\u00e7\u00e3o de gestantes, pu\u00e9rperas e seus filhos em situa\u00e7\u00e3o de vulnerabilidade em comunidades terap\u00eauticas [2018]<\/p>\n<p>&nbsp;<\/p>\n<h3><a href=\"https:\/\/www.dropbox.com\/s\/ns1buj43h7najmz\/Parecer%2001_2018%20-%20pessoa%20lgbt%20no%20sistema%20socioeducativo.pdf?dl=0\" target=\"_blank\" rel=\"noopener noreferrer\">&#8211; Parecer (n\u00ba 01\/2018)<\/a><\/h3>\n<p>Sobre a Resolu\u00e7\u00e3o SESP 18\/2018 que estabelece diretrizes e normativas para o atendimento da pessoa LGBT no \u00e2mbito do Sistema Socioeducativo do Estado de Minas Gerais [2018]<\/p>\n<p>&nbsp;<\/p>\n<h3><a href=\"https:\/\/www.dropbox.com\/s\/twbhvgftjqzw55y\/Policy%20Paper%20-%20Governan%C3%A7a%20Rio%20Doce.pdf?dl=0\" target=\"_blank\" rel=\"noopener noreferrer\">&#8211; Policy Paper (em parceria com a Conectas Direitos Humanos)<\/a><\/h3>\n<p>Transpar\u00eancia, participa\u00e7\u00e3o, responsabiliza\u00e7\u00e3o e repara\u00e7\u00e3o: uma proposta de reforma de governan\u00e7a para remedia\u00e7\u00e3o do desastre do Rio Doce [2018]<\/p>\n<p>&nbsp;<\/p>\n<h3><a href=\"https:\/\/www.dropbox.com\/s\/zwqdt1l4scxfm7z\/Relat%C3%B3rio%20para%20CIDH%20-%20Empresas%20e%20DH.pdf?dl=0\">&#8211; Relat\u00f3rio &#8211; Resposta Conjunta ao Question\u00e1rio de Consulta da Comiss\u00e3o Interamericana de Direitos Humanos<\/a><\/h3>\n<p>Em parceria com o Centro de Estudos sobre Justi\u00e7a de Transi\u00e7\u00e3o\/UFMG e o Grupo de Estudos sobre Direitos Internacional dos Direitos Humanos\/UFMG. Sobre &#8221; Empresas e Direitos Humanos: Par\u00e2metros Interamericanos &#8221; [2018]<\/p>\n<p>&nbsp;<\/p>\n<h3><a href=\"https:\/\/www.dropbox.com\/s\/04ubsjykigp4kru\/Amicus%20Curiae%20%28memorial%20de%29%20-%20a%20Corte%20Interamericana%20de%20Direitos%20Humanos%20na%20Opiniao%20Consultiva%20n%2024-17%20.pdf?dl=0\" target=\"_blank\" rel=\"noopener noreferrer\">&#8211; Amicus Curiae (memorial de) &#8211; \u00e0 Corte Interamericana de Direitos Humanos na Opini\u00e3o Consultiva n\u00ba 24\/17<\/a><\/h3>\n<p><span style=\"font-weight: 400;\">Opini\u00e3o Consultiva solicitada pelo Estado da Costa Rica \u00e0 Corte Interamericana de Direitos Humanos sobre identidade de g\u00eanero e orienta\u00e7\u00e3o sexual [2017]<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><a href=\"https:\/\/www.dropbox.com\/s\/rqggv4h9yg7njxb\/Denuncia%20CIDH%20territorio%20Guarani%20e%20Kaiow%C3%A1.pdf?dl=0\" target=\"_blank\" rel=\"noopener noreferrer\">&#8211; Den\u00fancia\/peti\u00e7\u00e3o (em parceria com Aty Guasu, Coletivo para o Acesso \u00e0 Justi\u00e7a Internacional e Conselho Indigenista Mission\u00e1rio)<\/a><\/h3>\n<p>Sobre as viola\u00e7\u00f5es sofridas pelo povo Guarani Kaiow\u00e1 em rela\u00e7\u00e3o ao territ\u00f3rio Guyraroka &#8211; protocolada na Comiss\u00e3o Interamericana de Direitos Humanos [2017]<\/p>\n<p>&nbsp;<\/p>\n<h3><a href=\"https:\/\/drive.google.com\/file\/d\/1LcyLO0IqrlIZQBz5NF-eI6f1C1TtGfhh\/view\">&#8211; Nota sobre consulta pr\u00e9via (n\u00ba 03\/2017)<\/a><\/h3>\n<p><span style=\"font-weight: 400;\">Sobre fundamentos normativos da prote\u00e7\u00e3o \u00e0s comunidades tradicionais e consulta pr\u00e9via e sua aplicabilidade \u00e0s comunidades de terreiro e suas pr\u00e1ticas religiosas. [2017]<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><a href=\"https:\/\/docs.wixstatic.com\/ugd\/c7de2b_bfcdbe7e56aa45ecaa63a321447c5c03.docx?dn=Peti\u00e7\u00e3o- Retifica\u00e7\u00e3o de registro civil - CdH.docx\">&#8211; Modelo de Peti\u00e7\u00e3o<\/a><\/h3>\n<p>Retifica\u00e7\u00e3o de registro civil [2017]<\/p>\n<p>&nbsp;<\/p>\n<h3><a href=\"https:\/\/drive.google.com\/file\/d\/1vweqz549zHoBYCpr7EsLNDG0CfsR-QIG\/view?usp=drive_link\" target=\"_blank\" rel=\"noopener noreferrer\">&#8211; Nota t\u00e9cnica (n\u00ba 01\/2017)<\/a><\/h3>\n<p>Sobre os fundamentos normativos que embasam a possibilidade de anistia pol\u00edtica coletiva a povos ind\u00edgenas, com destaque ao povo ind\u00edgena Krenak [2017]<\/p>\n<p>&nbsp;<\/p>\n<h3><a href=\"https:\/\/www.dropbox.com\/preview\/Publica%C3%A7%C3%B5es\/Nota%20T%C3%A9cnica%2002_2017%20-%20nova%20portaria%20m%C3%A3es%20e%20beb%C3%AAs.pdf?context=browse&amp;role=personal\" target=\"_blank\" rel=\"noopener noreferrer\">&#8211; Nota t\u00e9cnica (n\u00ba 02\/2017)<\/a><\/h3>\n<p>Referente \u00e0 minuta de portaria elaborada pela Vara C\u00edvel da Inf\u00e2ncia e da Juventude de Belo Horizonte\u200b [2017]<\/p>\n<p>&nbsp;<\/p>\n<h3><a href=\"https:\/\/www.dropbox.com\/s\/s52quqpbbhqxmsb\/Recomenda%C3%A7%C3%A3o%20-%20entrada%20de%20imigrantes%20na%20UFMG.pdf?dl=0\" target=\"_blank\" rel=\"noopener noreferrer\">&#8211; Recomenda\u00e7\u00e3o<\/a><\/h3>\n<p>Sobre o ingresso de imigrantes na UFMG [2017]<\/p>\n<p>&nbsp;<\/p>\n<h3><a href=\"https:\/\/www.dropbox.com\/s\/w2mn23joz2i315u\/Relat%C3%B3rio%20de%20Atividades%20-%20Povo%20Krenak.pdf?dl=0\" target=\"_blank\" rel=\"noopener noreferrer\">&#8211; Relat\u00f3rio de atividades<\/a><\/h3>\n<p>Sobre o projeto &#8220;Direito das popula\u00e7\u00f5es afetadas pelo rompimento da Barragem de Fund\u00e3o: o Povo Krenak&#8221; [2017]<\/p>\n<p>&nbsp;<\/p>\n<h3><a href=\"https:\/\/www.dropbox.com\/preview\/Publica%C3%A7%C3%B5es\/Direitos%20Humanos%20e%20efetiva%C3%A7%C3%A3o%20de%20cidadania%20retifica%C3%A7%C3%A3o%20de%20registro%20civil%20e%20de%20g%C3%AAnero%20para%20travestis%20e%20transexuais.pdf?context=browse&amp;role=personal\" target=\"_blank\" rel=\"noopener noreferrer\">&#8211; Direitos Humanos e efetiva\u00e7\u00e3o de cidadania<\/a><\/h3>\n<p><span style=\"font-weight: 400;\">Sobre a retifica\u00e7\u00e3o de registro civil para pessoas trans e o regime jur\u00eddico de uni\u00f5es homossexuais [2017]\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><a href=\"https:\/\/www.dropbox.com\/preview\/Publica%C3%A7%C3%B5es\/Nota%20T%C3%A9cnica%2003_2016%20-%20licenciamento%20amibiental%20e%20povos%20ind%C3%ADgenas.pdf?context=browse&amp;role=personal\"><span style=\"font-family: georgia, palatino, serif;\">&#8211; Nota t\u00e9cnica (n\u00ba 03\/2016)<\/span><\/a><\/h3>\n<p><span style=\"font-weight: 400;\">Sobre a an\u00e1lise do Projeto de Lei n\u00ba 654\/2015 do Senado Federal, \u00e0 luz dos direitos dos povos ind\u00edgenas. [2016]<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><a href=\"https:\/\/drive.google.com\/file\/d\/1Xy5SVs6sZZ89k0aOLgdbA6cUVAsOsut2\/view?usp=sharing\" target=\"_blank\" rel=\"noopener noreferrer\">&#8211; Nota t\u00e9cnica (n\u00ba 01\/2016)<\/a><\/h3>\n<p>Referente aos fundamentos normativos do instituto da consulta pr\u00e9via e sua aplicabilidade ao povo Krenak, face ao Termo de Transa\u00e7\u00e3o de Ajustamento de Conduta (TTAC) relativo ao rompimento da barragem de Fund\u00e3o [2016]<\/p>\n<p>&nbsp;<\/p>\n<h3><a href=\"https:\/\/www.dropbox.com\/s\/4b98tkl317fvtov\/Parecer%2001_2016%20-%20repara%C3%A7%C3%B5es%20da%20Corte%20IDH%20para%20povos%20ind%C3%ADgenas.pdf?dl=0\" target=\"_blank\" rel=\"noopener noreferrer\">&#8211; Parecer (n\u00ba 01\/2016)<\/a><\/h3>\n<p>Aponta recomenda\u00e7\u00f5es e pol\u00edticas p\u00fablicas decorrentes de senten\u00e7as proferidas pela Corte Interamericana de Direitos Humanos em casos que envolvem direitos humanos dos povos ind\u00edgenas [2016]<\/p>\n<p>&nbsp;<\/p>\n<h3><a href=\"https:\/\/www.dropbox.com\/s\/czrcn31dmjdy80c\/Resumo%20Executivo%20para%20CIDH%20-%20Direitos%20Culturais%20e%20Internet.pdf?dl=0\" target=\"_blank\" rel=\"noopener noreferrer\">&#8211; Resumo executivo<\/a><\/h3>\n<p>Sobre direitos culturais e internet no Brasil &#8211; apresentado \u00e0 Comiss\u00e3o Interamericana de Direitos Humanos (157\u00ba Per\u00edodo de Sess\u00f5es) [2016]<\/p>\n<p>&nbsp;<\/p>\n<h3><a href=\"https:\/\/www.dropbox.com\/s\/zp3ze8b7c5k8xsb\/Resumo%20Executivo%20para%20CIDH%20-%20pris%C3%A3o%20preventiva%20nas%20americas.pdf?dl=0\" target=\"_blank\" rel=\"noopener noreferrer\">&#8211; Resumo executivo<\/a><\/h3>\n<p>Sobre medidas para reduzir a pris\u00e3o preventiva nas Am\u00e9ricas\u200b &#8211; apresentado \u00e0 Comiss\u00e3o Interamericana de Direitos Humanos (157\u00ba Per\u00edodo de Sess\u00f5es) [2016]<\/p>\n<p>&nbsp;<\/p>\n<h3><a href=\"https:\/\/www.dropbox.com\/s\/9odmkol722e3omn\/A%20criminaliza%C3%A7%C3%A3o%20do%20pixo%20e%20seus%20impactos%20sobre%20o%20direito%20%C3%A0%20liberdade%20de%20express%C3%A3o%20-%20Parecer%20da%20CdH%20%281%29.pdf?dl=0\">&#8211; A Criminaliza\u00e7\u00e3o do Pixo e seus Impactos sobre o Direito \u00e0 Liberdade de Express\u00e3o &#8211; Parecer (n\u00ba 01\/2015)<\/a><\/h3>\n<p>Parecer sobre a criminaliza\u00e7\u00e3o do pixo no contexto urbano, para anexa\u00e7\u00e3o \u00e0 a\u00e7\u00e3o judicial referente ao caso \u201cOs Piores de Bel\u00f4\u201d [2015]<\/p>\n<p>&nbsp;<\/p>\n<h3><a href=\"https:\/\/drive.google.com\/file\/d\/0ByYnetejh0JAZV80eVhIUmZlZ28\/view?usp=sharing\" target=\"_blank\" rel=\"noopener noreferrer\">&#8211; Recomenda\u00e7\u00e3o<\/a><\/h3>\n<p>Sobre o PL 5555\/13, que tipifica a exposi\u00e7\u00e3o p\u00fablica da intimidade sexual [2015]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8211; Amicus Curiae (memorial de) &#8211; \u00e0 Corte Interamericana de Direitos Humanos na Opini\u00e3o Consultiva n\u00ba 32 Amicus curiae elaborado pela CdH\/UFMG na Opini\u00e3o Consultiva solicitada pelos Estados da Col\u00f4mbia e da Costa Rica sobre Emerg\u00eancia Clim\u00e1tica e Direitos Humanos [2024] &nbsp; &#8211; Amicus Curiae (memorial de) &#8211; \u00e0 Corte Interamericana de Direitos Humanos na Opini\u00e3o Consultiva n\u00ba 31 Amicus curiae elaborado por CdH\/UFMG, Diverso UFMG &#8211; N\u00facleo Jur\u00eddico de Diversidade Sexual e de G\u00eanero e N\u00facleo de Ensino, Pesquisa e Extens\u00e3o Conex\u00f5es de Saberes na Opini\u00e3o Consultiva solicitada pelo Estado da Argentina \u00e0 Corte Interamericana de Direitos Humanos sobre direito ao cuidado [2024] &nbsp; &#8211; Relat\u00f3rio Transpasse (2020-2022) Relat\u00f3rio de Atividades do Projeto Transpasse (2020-2022) [2023] &nbsp; &#8211; Resposta da CdH\/UFMG ao question\u00e1rio &#8220;setor extrativista, transi\u00e7\u00e3o justa e direitos humanos&#8221; Resposta da CdH\/UFMG ao Working Group of Business and Human Rights\u2019 call for input on the extractive sector, just transition and human rights\u00a0[em ingl\u00eas] [2023] &nbsp; &#8211; Direitos humanos e prote\u00e7\u00e3o ambiental em cadeias de fornecimento de min\u00e9rio de ferro Relat\u00f3rio t\u00e9cnico [em alem\u00e3o] [2022] &nbsp; &#8211; Relat\u00f3rio T\u00e9cnico COINTER Relat\u00f3rio T\u00e9cnico Cons\u00f3rcio-Observat\u00f3rio Interamericano (COINTER) [2022] &nbsp; &#8211; Aportes ao Processo de Negocia\u00e7\u00e3o do Instrumento Vinculante Sobre Empresas e Direitos Humanos no \u00c2mbito das Na\u00e7\u00f5es Unidas O documento, produzido em parceria com a DKA \u00c1ustria, ilustra algumas das disposi\u00e7\u00f5es da segunda vers\u00e3o revisada do rascunho de tratado vinculante, \u00e0 luz dos dois maiores desastres socioambientais e tecnol\u00f3gicos causados pelo setor de minera\u00e7\u00e3o no mundo, ambos recentes e ocorridos\u00a0 no Brasil [2021] &nbsp; &#8211; Contributions to the Process of Negotiation of the Binding Instrument on Business and Human Rights at the United Nations The document, produced in partnership with DKA Austria, illustrates some of the provisions of the second revised version of the draft binding treaty, in light of the two largest socio-environmental and technological disasters caused by the mining sector in the world, both recent and occurring in Brazil [2021] &nbsp; &#8211; Nota T\u00e9cnica sobre PL 4880\/2017 (sancionada como Lei 23.780\/2021): Nota t\u00e9cnica produzida em conjunto com a Coletiva M\u00e3es \u00d3rf\u00e3s, propondo altera\u00e7\u00f5es no texto original do PL. A lei sancionada institui a pol\u00edtica estadual de aten\u00e7\u00e3o a gestantes, pu\u00e9rperas e crian\u00e7as, em situa\u00e7\u00e3o de vulnerabilidade e riscos social e pessoal [2020] &nbsp; &#8211; Relat\u00f3rio do Projeto Transpasse Sobre a assist\u00eancia jur\u00eddica e psicossocial a pessoas trans e travestis, em Belo Horizonte, oferecida pela Cl\u00ednica [2019] &nbsp; &#8211; Amicus Curiae &#8211; ADI n\u00b0 5581 Sobre a\u00e7\u00e3o que trata da interrup\u00e7\u00e3o da gesta\u00e7\u00e3o, em rela\u00e7\u00e3o \u00e0 mulher infectada pelo zika v\u00edrus, dentre outros assuntos [2019] &nbsp; &#8211; Amicus Curiae &#8211; ADPF n\u00b0 442 Sobre a\u00e7\u00e3o que trata da interrup\u00e7\u00e3o da gravidez at\u00e9 a 12\u00aa semana de gesta\u00e7\u00e3o [2018] &nbsp; &#8211; Nota t\u00e9cnica conjunta\u00a0 Sobre direitos de m\u00e3es e beb\u00eas ao tratamento em liberdade. Referente \u00e0 proposta de interna\u00e7\u00e3o de gestantes, pu\u00e9rperas e seus filhos em situa\u00e7\u00e3o de vulnerabilidade em comunidades terap\u00eauticas [2018] &nbsp; &#8211; Parecer (n\u00ba 01\/2018) Sobre a Resolu\u00e7\u00e3o SESP 18\/2018 que estabelece diretrizes e normativas para o atendimento da pessoa LGBT no \u00e2mbito do Sistema Socioeducativo do Estado de Minas Gerais [2018] &nbsp; &#8211; Policy Paper (em parceria com a Conectas Direitos Humanos) Transpar\u00eancia, participa\u00e7\u00e3o, responsabiliza\u00e7\u00e3o e repara\u00e7\u00e3o: uma proposta de reforma de governan\u00e7a para remedia\u00e7\u00e3o do desastre do Rio Doce [2018] &nbsp; &#8211; Relat\u00f3rio &#8211; Resposta Conjunta ao Question\u00e1rio de Consulta da Comiss\u00e3o Interamericana de Direitos Humanos Em parceria com o Centro de Estudos sobre Justi\u00e7a de Transi\u00e7\u00e3o\/UFMG e o Grupo de Estudos sobre Direitos Internacional dos Direitos Humanos\/UFMG. Sobre &#8221; Empresas e Direitos Humanos: Par\u00e2metros Interamericanos &#8221; [2018] &nbsp; &#8211; Amicus Curiae (memorial de) &#8211; \u00e0 Corte Interamericana de Direitos Humanos na Opini\u00e3o Consultiva n\u00ba 24\/17 Opini\u00e3o Consultiva solicitada pelo Estado da Costa Rica \u00e0 Corte Interamericana de Direitos Humanos sobre identidade de g\u00eanero e orienta\u00e7\u00e3o sexual [2017] &nbsp; &#8211; Den\u00fancia\/peti\u00e7\u00e3o (em parceria com Aty Guasu, Coletivo para o Acesso \u00e0 Justi\u00e7a Internacional e Conselho Indigenista Mission\u00e1rio) Sobre as viola\u00e7\u00f5es sofridas pelo povo Guarani Kaiow\u00e1 em rela\u00e7\u00e3o ao territ\u00f3rio Guyraroka &#8211; protocolada na Comiss\u00e3o Interamericana de Direitos Humanos [2017] &nbsp; &#8211; Nota sobre consulta pr\u00e9via (n\u00ba 03\/2017) Sobre fundamentos normativos da prote\u00e7\u00e3o \u00e0s comunidades tradicionais e consulta pr\u00e9via e sua aplicabilidade \u00e0s comunidades de terreiro e suas pr\u00e1ticas religiosas. [2017] &nbsp; &#8211; Modelo de Peti\u00e7\u00e3o Retifica\u00e7\u00e3o de registro civil [2017] &nbsp; &#8211; Nota t\u00e9cnica (n\u00ba 01\/2017) Sobre os fundamentos normativos que embasam a possibilidade de anistia pol\u00edtica coletiva a povos ind\u00edgenas, com destaque ao povo ind\u00edgena Krenak [2017] &nbsp; &#8211; Nota t\u00e9cnica (n\u00ba 02\/2017) Referente \u00e0 minuta de portaria elaborada pela Vara C\u00edvel da Inf\u00e2ncia e da Juventude de Belo Horizonte\u200b [2017] &nbsp; &#8211; Recomenda\u00e7\u00e3o Sobre o ingresso de imigrantes na UFMG [2017] &nbsp; &#8211; Relat\u00f3rio de atividades Sobre o projeto &#8220;Direito das popula\u00e7\u00f5es afetadas pelo rompimento da Barragem de Fund\u00e3o: o Povo Krenak&#8221; [2017] &nbsp; &#8211; Direitos Humanos e efetiva\u00e7\u00e3o de cidadania Sobre a retifica\u00e7\u00e3o de registro civil para pessoas trans e o regime jur\u00eddico de uni\u00f5es homossexuais [2017]\u00a0 &nbsp; &#8211; Nota t\u00e9cnica (n\u00ba 03\/2016) Sobre a an\u00e1lise do Projeto de Lei n\u00ba 654\/2015 do Senado Federal, \u00e0 luz dos direitos dos povos ind\u00edgenas. [2016] &nbsp; &#8211; Nota t\u00e9cnica (n\u00ba 01\/2016) Referente aos fundamentos normativos do instituto da consulta pr\u00e9via e sua aplicabilidade ao povo Krenak, face ao Termo de Transa\u00e7\u00e3o de Ajustamento de Conduta (TTAC) relativo ao rompimento da barragem de Fund\u00e3o [2016] &nbsp; &#8211; Parecer (n\u00ba 01\/2016) Aponta recomenda\u00e7\u00f5es e pol\u00edticas p\u00fablicas decorrentes de senten\u00e7as proferidas pela Corte Interamericana de Direitos Humanos em casos que envolvem direitos humanos dos povos ind\u00edgenas [2016] &nbsp; &#8211; Resumo executivo Sobre direitos culturais e internet no Brasil &#8211; apresentado \u00e0 Comiss\u00e3o Interamericana de Direitos Humanos (157\u00ba Per\u00edodo de Sess\u00f5es) [2016] &nbsp; &#8211; Resumo executivo Sobre medidas para reduzir a pris\u00e3o preventiva nas Am\u00e9ricas\u200b &#8211; apresentado \u00e0 Comiss\u00e3o Interamericana de Direitos Humanos (157\u00ba Per\u00edodo de Sess\u00f5es) [2016] &nbsp; &#8211; A Criminaliza\u00e7\u00e3o do Pixo e seus Impactos sobre o Direito \u00e0 Liberdade de Express\u00e3o &#8211; Parecer (n\u00ba 01\/2015) Parecer sobre a criminaliza\u00e7\u00e3o do pixo no contexto urbano, para anexa\u00e7\u00e3o \u00e0 a\u00e7\u00e3o judicial referente ao caso \u201cOs Piores de Bel\u00f4\u201d [2015] &nbsp; &#8211; Recomenda\u00e7\u00e3o Sobre o PL 5555\/13, que tipifica a exposi\u00e7\u00e3o p\u00fablica da intimidade sexual [2015]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-56","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Produ\u00e7\u00f5es T\u00e9cnicas - Cl\u00ednica de Direitos Humanos da UFMG<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/clinicadh.direito.ufmg.br\/index.php\/tecnicas\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Produ\u00e7\u00f5es T\u00e9cnicas - Cl\u00ednica de Direitos Humanos da UFMG\" \/>\n<meta property=\"og:description\" content=\"&#8211; Amicus Curiae (memorial de) &#8211; \u00e0 Corte Interamericana de Direitos Humanos na Opini\u00e3o Consultiva n\u00ba 32 Amicus curiae elaborado pela CdH\/UFMG na Opini\u00e3o Consultiva solicitada pelos Estados da Col\u00f4mbia e da Costa Rica sobre Emerg\u00eancia Clim\u00e1tica e Direitos Humanos [2024] &nbsp; &#8211; Amicus Curiae (memorial de) &#8211; \u00e0 Corte Interamericana de Direitos Humanos na Opini\u00e3o Consultiva n\u00ba 31 Amicus curiae elaborado por CdH\/UFMG, Diverso UFMG &#8211; N\u00facleo Jur\u00eddico de Diversidade Sexual e de G\u00eanero e N\u00facleo de Ensino, Pesquisa e Extens\u00e3o Conex\u00f5es de Saberes na Opini\u00e3o Consultiva solicitada pelo Estado da Argentina \u00e0 Corte Interamericana de Direitos Humanos sobre direito ao cuidado [2024] &nbsp; &#8211; Relat\u00f3rio Transpasse (2020-2022) Relat\u00f3rio de Atividades do Projeto Transpasse (2020-2022) [2023] &nbsp; &#8211; Resposta da CdH\/UFMG ao question\u00e1rio &#8220;setor extrativista, transi\u00e7\u00e3o justa e direitos humanos&#8221; Resposta da CdH\/UFMG ao Working Group of Business and Human Rights\u2019 call for input on the extractive sector, just transition and human rights\u00a0[em ingl\u00eas] [2023] &nbsp; &#8211; Direitos humanos e prote\u00e7\u00e3o ambiental em cadeias de fornecimento de min\u00e9rio de ferro Relat\u00f3rio t\u00e9cnico [em alem\u00e3o] [2022] &nbsp; &#8211; Relat\u00f3rio T\u00e9cnico COINTER Relat\u00f3rio T\u00e9cnico Cons\u00f3rcio-Observat\u00f3rio Interamericano (COINTER) [2022] &nbsp; &#8211; Aportes ao Processo de Negocia\u00e7\u00e3o do Instrumento Vinculante Sobre Empresas e Direitos Humanos no \u00c2mbito das Na\u00e7\u00f5es Unidas O documento, produzido em parceria com a DKA \u00c1ustria, ilustra algumas das disposi\u00e7\u00f5es da segunda vers\u00e3o revisada do rascunho de tratado vinculante, \u00e0 luz dos dois maiores desastres socioambientais e tecnol\u00f3gicos causados pelo setor de minera\u00e7\u00e3o no mundo, ambos recentes e ocorridos\u00a0 no Brasil [2021] &nbsp; &#8211; Contributions to the Process of Negotiation of the Binding Instrument on Business and Human Rights at the United Nations The document, produced in partnership with DKA Austria, illustrates some of the provisions of the second revised version of the draft binding treaty, in light of the two largest socio-environmental and technological disasters caused by the mining sector in the world, both recent and occurring in Brazil [2021] &nbsp; &#8211; Nota T\u00e9cnica sobre PL 4880\/2017 (sancionada como Lei 23.780\/2021): Nota t\u00e9cnica produzida em conjunto com a Coletiva M\u00e3es \u00d3rf\u00e3s, propondo altera\u00e7\u00f5es no texto original do PL. A lei sancionada institui a pol\u00edtica estadual de aten\u00e7\u00e3o a gestantes, pu\u00e9rperas e crian\u00e7as, em situa\u00e7\u00e3o de vulnerabilidade e riscos social e pessoal [2020] &nbsp; &#8211; Relat\u00f3rio do Projeto Transpasse Sobre a assist\u00eancia jur\u00eddica e psicossocial a pessoas trans e travestis, em Belo Horizonte, oferecida pela Cl\u00ednica [2019] &nbsp; &#8211; Amicus Curiae &#8211; ADI n\u00b0 5581 Sobre a\u00e7\u00e3o que trata da interrup\u00e7\u00e3o da gesta\u00e7\u00e3o, em rela\u00e7\u00e3o \u00e0 mulher infectada pelo zika v\u00edrus, dentre outros assuntos [2019] &nbsp; &#8211; Amicus Curiae &#8211; ADPF n\u00b0 442 Sobre a\u00e7\u00e3o que trata da interrup\u00e7\u00e3o da gravidez at\u00e9 a 12\u00aa semana de gesta\u00e7\u00e3o [2018] &nbsp; &#8211; Nota t\u00e9cnica conjunta\u00a0 Sobre direitos de m\u00e3es e beb\u00eas ao tratamento em liberdade. Referente \u00e0 proposta de interna\u00e7\u00e3o de gestantes, pu\u00e9rperas e seus filhos em situa\u00e7\u00e3o de vulnerabilidade em comunidades terap\u00eauticas [2018] &nbsp; &#8211; Parecer (n\u00ba 01\/2018) Sobre a Resolu\u00e7\u00e3o SESP 18\/2018 que estabelece diretrizes e normativas para o atendimento da pessoa LGBT no \u00e2mbito do Sistema Socioeducativo do Estado de Minas Gerais [2018] &nbsp; &#8211; Policy Paper (em parceria com a Conectas Direitos Humanos) Transpar\u00eancia, participa\u00e7\u00e3o, responsabiliza\u00e7\u00e3o e repara\u00e7\u00e3o: uma proposta de reforma de governan\u00e7a para remedia\u00e7\u00e3o do desastre do Rio Doce [2018] &nbsp; &#8211; Relat\u00f3rio &#8211; Resposta Conjunta ao Question\u00e1rio de Consulta da Comiss\u00e3o Interamericana de Direitos Humanos Em parceria com o Centro de Estudos sobre Justi\u00e7a de Transi\u00e7\u00e3o\/UFMG e o Grupo de Estudos sobre Direitos Internacional dos Direitos Humanos\/UFMG. Sobre &#8221; Empresas e Direitos Humanos: Par\u00e2metros Interamericanos &#8221; [2018] &nbsp; &#8211; Amicus Curiae (memorial de) &#8211; \u00e0 Corte Interamericana de Direitos Humanos na Opini\u00e3o Consultiva n\u00ba 24\/17 Opini\u00e3o Consultiva solicitada pelo Estado da Costa Rica \u00e0 Corte Interamericana de Direitos Humanos sobre identidade de g\u00eanero e orienta\u00e7\u00e3o sexual [2017] &nbsp; &#8211; Den\u00fancia\/peti\u00e7\u00e3o (em parceria com Aty Guasu, Coletivo para o Acesso \u00e0 Justi\u00e7a Internacional e Conselho Indigenista Mission\u00e1rio) Sobre as viola\u00e7\u00f5es sofridas pelo povo Guarani Kaiow\u00e1 em rela\u00e7\u00e3o ao territ\u00f3rio Guyraroka &#8211; protocolada na Comiss\u00e3o Interamericana de Direitos Humanos [2017] &nbsp; &#8211; Nota sobre consulta pr\u00e9via (n\u00ba 03\/2017) Sobre fundamentos normativos da prote\u00e7\u00e3o \u00e0s comunidades tradicionais e consulta pr\u00e9via e sua aplicabilidade \u00e0s comunidades de terreiro e suas pr\u00e1ticas religiosas. [2017] &nbsp; &#8211; Modelo de Peti\u00e7\u00e3o Retifica\u00e7\u00e3o de registro civil [2017] &nbsp; &#8211; Nota t\u00e9cnica (n\u00ba 01\/2017) Sobre os fundamentos normativos que embasam a possibilidade de anistia pol\u00edtica coletiva a povos ind\u00edgenas, com destaque ao povo ind\u00edgena Krenak [2017] &nbsp; &#8211; Nota t\u00e9cnica (n\u00ba 02\/2017) Referente \u00e0 minuta de portaria elaborada pela Vara C\u00edvel da Inf\u00e2ncia e da Juventude de Belo Horizonte\u200b [2017] &nbsp; &#8211; Recomenda\u00e7\u00e3o Sobre o ingresso de imigrantes na UFMG [2017] &nbsp; &#8211; Relat\u00f3rio de atividades Sobre o projeto &#8220;Direito das popula\u00e7\u00f5es afetadas pelo rompimento da Barragem de Fund\u00e3o: o Povo Krenak&#8221; [2017] &nbsp; &#8211; Direitos Humanos e efetiva\u00e7\u00e3o de cidadania Sobre a retifica\u00e7\u00e3o de registro civil para pessoas trans e o regime jur\u00eddico de uni\u00f5es homossexuais [2017]\u00a0 &nbsp; &#8211; Nota t\u00e9cnica (n\u00ba 03\/2016) Sobre a an\u00e1lise do Projeto de Lei n\u00ba 654\/2015 do Senado Federal, \u00e0 luz dos direitos dos povos ind\u00edgenas. [2016] &nbsp; &#8211; Nota t\u00e9cnica (n\u00ba 01\/2016) Referente aos fundamentos normativos do instituto da consulta pr\u00e9via e sua aplicabilidade ao povo Krenak, face ao Termo de Transa\u00e7\u00e3o de Ajustamento de Conduta (TTAC) relativo ao rompimento da barragem de Fund\u00e3o [2016] &nbsp; &#8211; Parecer (n\u00ba 01\/2016) Aponta recomenda\u00e7\u00f5es e pol\u00edticas p\u00fablicas decorrentes de senten\u00e7as proferidas pela Corte Interamericana de Direitos Humanos em casos que envolvem direitos humanos dos povos ind\u00edgenas [2016] &nbsp; &#8211; Resumo executivo Sobre direitos culturais e internet no Brasil &#8211; apresentado \u00e0 Comiss\u00e3o Interamericana de Direitos Humanos (157\u00ba Per\u00edodo de Sess\u00f5es) [2016] &nbsp; &#8211; Resumo executivo Sobre medidas para reduzir a pris\u00e3o preventiva nas Am\u00e9ricas\u200b &#8211; apresentado \u00e0 Comiss\u00e3o Interamericana de Direitos Humanos (157\u00ba Per\u00edodo de Sess\u00f5es) [2016] &nbsp; &#8211; A Criminaliza\u00e7\u00e3o do Pixo e seus Impactos sobre o Direito \u00e0 Liberdade de Express\u00e3o &#8211; Parecer (n\u00ba 01\/2015) Parecer sobre a criminaliza\u00e7\u00e3o do pixo no contexto urbano, para anexa\u00e7\u00e3o \u00e0 a\u00e7\u00e3o judicial referente ao caso \u201cOs Piores de Bel\u00f4\u201d [2015] &nbsp; &#8211; Recomenda\u00e7\u00e3o Sobre o PL 5555\/13, que tipifica a exposi\u00e7\u00e3o p\u00fablica da intimidade sexual [2015]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/clinicadh.direito.ufmg.br\/index.php\/tecnicas\/\" \/>\n<meta property=\"og:site_name\" content=\"Cl\u00ednica de Direitos Humanos da UFMG\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/cdhufmg\/?eid=ARBDSQLce69q0_8v--9A5W6uQzSMctjXi-aHCPLj-fZRI0TKZQaBy-H1YgM9D-FJc2tGPQyTyAg3EYce\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-26T11:29:14+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/clinicadh.direito.ufmg.br\/index.php\/tecnicas\/\",\"url\":\"https:\/\/clinicadh.direito.ufmg.br\/index.php\/tecnicas\/\",\"name\":\"Produ\u00e7\u00f5es T\u00e9cnicas - Cl\u00ednica de Direitos Humanos da UFMG\",\"isPartOf\":{\"@id\":\"https:\/\/clinicadh.direito.ufmg.br\/#website\"},\"datePublished\":\"2018-11-30T22:46:43+00:00\",\"dateModified\":\"2024-04-26T11:29:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/clinicadh.direito.ufmg.br\/index.php\/tecnicas\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/clinicadh.direito.ufmg.br\/index.php\/tecnicas\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/clinicadh.direito.ufmg.br\/index.php\/tecnicas\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/clinicadh.direito.ufmg.br\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produ\u00e7\u00f5es T\u00e9cnicas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/clinicadh.direito.ufmg.br\/#website\",\"url\":\"https:\/\/clinicadh.direito.ufmg.br\/\",\"name\":\"Cl\u00ednica de Direitos Humanos da UFMG\",\"description\":\"Cl\u00ednica de Direitos Humanos da Universidade Federal de Minas Gerais\",\"publisher\":{\"@id\":\"https:\/\/clinicadh.direito.ufmg.br\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/clinicadh.direito.ufmg.br\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/clinicadh.direito.ufmg.br\/#organization\",\"name\":\"Cl\u00ednica de Direitos Humanos da UFMG\",\"url\":\"https:\/\/clinicadh.direito.ufmg.br\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/clinicadh.direito.ufmg.br\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/clinicadh.direito.ufmg.br\/wp-content\/uploads\/2015\/06\/c.jpg\",\"contentUrl\":\"https:\/\/clinicadh.direito.ufmg.br\/wp-content\/uploads\/2015\/06\/c.jpg\",\"width\":1200,\"height\":500,\"caption\":\"Cl\u00ednica de Direitos Humanos da UFMG\"},\"image\":{\"@id\":\"https:\/\/clinicadh.direito.ufmg.br\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/cdhufmg\/?eid=ARBDSQLce69q0_8v--9A5W6uQzSMctjXi-aHCPLj-fZRI0TKZQaBy-H1YgM9D-FJc2tGPQyTyAg3EYce\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Produ\u00e7\u00f5es T\u00e9cnicas - Cl\u00ednica de Direitos Humanos da UFMG","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/clinicadh.direito.ufmg.br\/index.php\/tecnicas\/","og_locale":"pt_BR","og_type":"article","og_title":"Produ\u00e7\u00f5es T\u00e9cnicas - Cl\u00ednica de Direitos Humanos da UFMG","og_description":"&#8211; Amicus Curiae (memorial de) &#8211; \u00e0 Corte Interamericana de Direitos Humanos na Opini\u00e3o Consultiva n\u00ba 32 Amicus curiae elaborado pela CdH\/UFMG na Opini\u00e3o Consultiva solicitada pelos Estados da Col\u00f4mbia e da Costa Rica sobre Emerg\u00eancia Clim\u00e1tica e Direitos Humanos [2024] &nbsp; &#8211; Amicus Curiae (memorial de) &#8211; \u00e0 Corte Interamericana de Direitos Humanos na Opini\u00e3o Consultiva n\u00ba 31 Amicus curiae elaborado por CdH\/UFMG, Diverso UFMG &#8211; N\u00facleo Jur\u00eddico de Diversidade Sexual e de G\u00eanero e N\u00facleo de Ensino, Pesquisa e Extens\u00e3o Conex\u00f5es de Saberes na Opini\u00e3o Consultiva solicitada pelo Estado da Argentina \u00e0 Corte Interamericana de Direitos Humanos sobre direito ao cuidado [2024] &nbsp; &#8211; Relat\u00f3rio Transpasse (2020-2022) Relat\u00f3rio de Atividades do Projeto Transpasse (2020-2022) [2023] &nbsp; &#8211; Resposta da CdH\/UFMG ao question\u00e1rio &#8220;setor extrativista, transi\u00e7\u00e3o justa e direitos humanos&#8221; Resposta da CdH\/UFMG ao Working Group of Business and Human Rights\u2019 call for input on the extractive sector, just transition and human rights\u00a0[em ingl\u00eas] [2023] &nbsp; &#8211; Direitos humanos e prote\u00e7\u00e3o ambiental em cadeias de fornecimento de min\u00e9rio de ferro Relat\u00f3rio t\u00e9cnico [em alem\u00e3o] [2022] &nbsp; &#8211; Relat\u00f3rio T\u00e9cnico COINTER Relat\u00f3rio T\u00e9cnico Cons\u00f3rcio-Observat\u00f3rio Interamericano (COINTER) [2022] &nbsp; &#8211; Aportes ao Processo de Negocia\u00e7\u00e3o do Instrumento Vinculante Sobre Empresas e Direitos Humanos no \u00c2mbito das Na\u00e7\u00f5es Unidas O documento, produzido em parceria com a DKA \u00c1ustria, ilustra algumas das disposi\u00e7\u00f5es da segunda vers\u00e3o revisada do rascunho de tratado vinculante, \u00e0 luz dos dois maiores desastres socioambientais e tecnol\u00f3gicos causados pelo setor de minera\u00e7\u00e3o no mundo, ambos recentes e ocorridos\u00a0 no Brasil [2021] &nbsp; &#8211; Contributions to the Process of Negotiation of the Binding Instrument on Business and Human Rights at the United Nations The document, produced in partnership with DKA Austria, illustrates some of the provisions of the second revised version of the draft binding treaty, in light of the two largest socio-environmental and technological disasters caused by the mining sector in the world, both recent and occurring in Brazil [2021] &nbsp; &#8211; Nota T\u00e9cnica sobre PL 4880\/2017 (sancionada como Lei 23.780\/2021): Nota t\u00e9cnica produzida em conjunto com a Coletiva M\u00e3es \u00d3rf\u00e3s, propondo altera\u00e7\u00f5es no texto original do PL. A lei sancionada institui a pol\u00edtica estadual de aten\u00e7\u00e3o a gestantes, pu\u00e9rperas e crian\u00e7as, em situa\u00e7\u00e3o de vulnerabilidade e riscos social e pessoal [2020] &nbsp; &#8211; Relat\u00f3rio do Projeto Transpasse Sobre a assist\u00eancia jur\u00eddica e psicossocial a pessoas trans e travestis, em Belo Horizonte, oferecida pela Cl\u00ednica [2019] &nbsp; &#8211; Amicus Curiae &#8211; ADI n\u00b0 5581 Sobre a\u00e7\u00e3o que trata da interrup\u00e7\u00e3o da gesta\u00e7\u00e3o, em rela\u00e7\u00e3o \u00e0 mulher infectada pelo zika v\u00edrus, dentre outros assuntos [2019] &nbsp; &#8211; Amicus Curiae &#8211; ADPF n\u00b0 442 Sobre a\u00e7\u00e3o que trata da interrup\u00e7\u00e3o da gravidez at\u00e9 a 12\u00aa semana de gesta\u00e7\u00e3o [2018] &nbsp; &#8211; Nota t\u00e9cnica conjunta\u00a0 Sobre direitos de m\u00e3es e beb\u00eas ao tratamento em liberdade. Referente \u00e0 proposta de interna\u00e7\u00e3o de gestantes, pu\u00e9rperas e seus filhos em situa\u00e7\u00e3o de vulnerabilidade em comunidades terap\u00eauticas [2018] &nbsp; &#8211; Parecer (n\u00ba 01\/2018) Sobre a Resolu\u00e7\u00e3o SESP 18\/2018 que estabelece diretrizes e normativas para o atendimento da pessoa LGBT no \u00e2mbito do Sistema Socioeducativo do Estado de Minas Gerais [2018] &nbsp; &#8211; Policy Paper (em parceria com a Conectas Direitos Humanos) Transpar\u00eancia, participa\u00e7\u00e3o, responsabiliza\u00e7\u00e3o e repara\u00e7\u00e3o: uma proposta de reforma de governan\u00e7a para remedia\u00e7\u00e3o do desastre do Rio Doce [2018] &nbsp; &#8211; Relat\u00f3rio &#8211; Resposta Conjunta ao Question\u00e1rio de Consulta da Comiss\u00e3o Interamericana de Direitos Humanos Em parceria com o Centro de Estudos sobre Justi\u00e7a de Transi\u00e7\u00e3o\/UFMG e o Grupo de Estudos sobre Direitos Internacional dos Direitos Humanos\/UFMG. Sobre &#8221; Empresas e Direitos Humanos: Par\u00e2metros Interamericanos &#8221; [2018] &nbsp; &#8211; Amicus Curiae (memorial de) &#8211; \u00e0 Corte Interamericana de Direitos Humanos na Opini\u00e3o Consultiva n\u00ba 24\/17 Opini\u00e3o Consultiva solicitada pelo Estado da Costa Rica \u00e0 Corte Interamericana de Direitos Humanos sobre identidade de g\u00eanero e orienta\u00e7\u00e3o sexual [2017] &nbsp; &#8211; Den\u00fancia\/peti\u00e7\u00e3o (em parceria com Aty Guasu, Coletivo para o Acesso \u00e0 Justi\u00e7a Internacional e Conselho Indigenista Mission\u00e1rio) Sobre as viola\u00e7\u00f5es sofridas pelo povo Guarani Kaiow\u00e1 em rela\u00e7\u00e3o ao territ\u00f3rio Guyraroka &#8211; protocolada na Comiss\u00e3o Interamericana de Direitos Humanos [2017] &nbsp; &#8211; Nota sobre consulta pr\u00e9via (n\u00ba 03\/2017) Sobre fundamentos normativos da prote\u00e7\u00e3o \u00e0s comunidades tradicionais e consulta pr\u00e9via e sua aplicabilidade \u00e0s comunidades de terreiro e suas pr\u00e1ticas religiosas. [2017] &nbsp; &#8211; Modelo de Peti\u00e7\u00e3o Retifica\u00e7\u00e3o de registro civil [2017] &nbsp; &#8211; Nota t\u00e9cnica (n\u00ba 01\/2017) Sobre os fundamentos normativos que embasam a possibilidade de anistia pol\u00edtica coletiva a povos ind\u00edgenas, com destaque ao povo ind\u00edgena Krenak [2017] &nbsp; &#8211; Nota t\u00e9cnica (n\u00ba 02\/2017) Referente \u00e0 minuta de portaria elaborada pela Vara C\u00edvel da Inf\u00e2ncia e da Juventude de Belo Horizonte\u200b [2017] &nbsp; &#8211; Recomenda\u00e7\u00e3o Sobre o ingresso de imigrantes na UFMG [2017] &nbsp; &#8211; Relat\u00f3rio de atividades Sobre o projeto &#8220;Direito das popula\u00e7\u00f5es afetadas pelo rompimento da Barragem de Fund\u00e3o: o Povo Krenak&#8221; [2017] &nbsp; &#8211; Direitos Humanos e efetiva\u00e7\u00e3o de cidadania Sobre a retifica\u00e7\u00e3o de registro civil para pessoas trans e o regime jur\u00eddico de uni\u00f5es homossexuais [2017]\u00a0 &nbsp; &#8211; Nota t\u00e9cnica (n\u00ba 03\/2016) Sobre a an\u00e1lise do Projeto de Lei n\u00ba 654\/2015 do Senado Federal, \u00e0 luz dos direitos dos povos ind\u00edgenas. [2016] &nbsp; &#8211; Nota t\u00e9cnica (n\u00ba 01\/2016) Referente aos fundamentos normativos do instituto da consulta pr\u00e9via e sua aplicabilidade ao povo Krenak, face ao Termo de Transa\u00e7\u00e3o de Ajustamento de Conduta (TTAC) relativo ao rompimento da barragem de Fund\u00e3o [2016] &nbsp; &#8211; Parecer (n\u00ba 01\/2016) Aponta recomenda\u00e7\u00f5es e pol\u00edticas p\u00fablicas decorrentes de senten\u00e7as proferidas pela Corte Interamericana de Direitos Humanos em casos que envolvem direitos humanos dos povos ind\u00edgenas [2016] &nbsp; &#8211; Resumo executivo Sobre direitos culturais e internet no Brasil &#8211; apresentado \u00e0 Comiss\u00e3o Interamericana de Direitos Humanos (157\u00ba Per\u00edodo de Sess\u00f5es) [2016] &nbsp; &#8211; Resumo executivo Sobre medidas para reduzir a pris\u00e3o preventiva nas Am\u00e9ricas\u200b &#8211; apresentado \u00e0 Comiss\u00e3o Interamericana de Direitos Humanos (157\u00ba Per\u00edodo de Sess\u00f5es) [2016] &nbsp; &#8211; A Criminaliza\u00e7\u00e3o do Pixo e seus Impactos sobre o Direito \u00e0 Liberdade de Express\u00e3o &#8211; Parecer (n\u00ba 01\/2015) Parecer sobre a criminaliza\u00e7\u00e3o do pixo no contexto urbano, para anexa\u00e7\u00e3o \u00e0 a\u00e7\u00e3o judicial referente ao caso \u201cOs Piores de Bel\u00f4\u201d [2015] &nbsp; &#8211; Recomenda\u00e7\u00e3o Sobre o PL 5555\/13, que tipifica a exposi\u00e7\u00e3o p\u00fablica da intimidade sexual [2015]","og_url":"https:\/\/clinicadh.direito.ufmg.br\/index.php\/tecnicas\/","og_site_name":"Cl\u00ednica de Direitos Humanos da UFMG","article_publisher":"https:\/\/www.facebook.com\/cdhufmg\/?eid=ARBDSQLce69q0_8v--9A5W6uQzSMctjXi-aHCPLj-fZRI0TKZQaBy-H1YgM9D-FJc2tGPQyTyAg3EYce","article_modified_time":"2024-04-26T11:29:14+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. tempo de leitura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/clinicadh.direito.ufmg.br\/index.php\/tecnicas\/","url":"https:\/\/clinicadh.direito.ufmg.br\/index.php\/tecnicas\/","name":"Produ\u00e7\u00f5es T\u00e9cnicas - Cl\u00ednica de Direitos Humanos da UFMG","isPartOf":{"@id":"https:\/\/clinicadh.direito.ufmg.br\/#website"},"datePublished":"2018-11-30T22:46:43+00:00","dateModified":"2024-04-26T11:29:14+00:00","breadcrumb":{"@id":"https:\/\/clinicadh.direito.ufmg.br\/index.php\/tecnicas\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/clinicadh.direito.ufmg.br\/index.php\/tecnicas\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/clinicadh.direito.ufmg.br\/index.php\/tecnicas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/clinicadh.direito.ufmg.br\/"},{"@type":"ListItem","position":2,"name":"Produ\u00e7\u00f5es T\u00e9cnicas"}]},{"@type":"WebSite","@id":"https:\/\/clinicadh.direito.ufmg.br\/#website","url":"https:\/\/clinicadh.direito.ufmg.br\/","name":"Cl\u00ednica de Direitos Humanos da UFMG","description":"Cl\u00ednica de Direitos Humanos da Universidade Federal de Minas Gerais","publisher":{"@id":"https:\/\/clinicadh.direito.ufmg.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/clinicadh.direito.ufmg.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/clinicadh.direito.ufmg.br\/#organization","name":"Cl\u00ednica de Direitos Humanos da UFMG","url":"https:\/\/clinicadh.direito.ufmg.br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/clinicadh.direito.ufmg.br\/#\/schema\/logo\/image\/","url":"https:\/\/clinicadh.direito.ufmg.br\/wp-content\/uploads\/2015\/06\/c.jpg","contentUrl":"https:\/\/clinicadh.direito.ufmg.br\/wp-content\/uploads\/2015\/06\/c.jpg","width":1200,"height":500,"caption":"Cl\u00ednica de Direitos Humanos da UFMG"},"image":{"@id":"https:\/\/clinicadh.direito.ufmg.br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/cdhufmg\/?eid=ARBDSQLce69q0_8v--9A5W6uQzSMctjXi-aHCPLj-fZRI0TKZQaBy-H1YgM9D-FJc2tGPQyTyAg3EYce"]}]}},"_links":{"self":[{"href":"https:\/\/clinicadh.direito.ufmg.br\/index.php\/wp-json\/wp\/v2\/pages\/56","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/clinicadh.direito.ufmg.br\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/clinicadh.direito.ufmg.br\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/clinicadh.direito.ufmg.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/clinicadh.direito.ufmg.br\/index.php\/wp-json\/wp\/v2\/comments?post=56"}],"version-history":[{"count":7,"href":"https:\/\/clinicadh.direito.ufmg.br\/index.php\/wp-json\/wp\/v2\/pages\/56\/revisions"}],"predecessor-version":[{"id":1876,"href":"https:\/\/clinicadh.direito.ufmg.br\/index.php\/wp-json\/wp\/v2\/pages\/56\/revisions\/1876"}],"wp:attachment":[{"href":"https:\/\/clinicadh.direito.ufmg.br\/index.php\/wp-json\/wp\/v2\/media?parent=56"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}